{"id":6908,"date":"2026-06-15T08:45:00","date_gmt":"2026-06-15T07:45:00","guid":{"rendered":"https:\/\/www.univ-mosta.dz\/vrpghr\/?post_type=news&#038;p=6908"},"modified":"2026-07-01T14:49:19","modified_gmt":"2026-07-01T13:49:19","slug":"avis-de-soutenance-de-these-de-doctorat-madame-founas-fatima-zohra-le-08-juillet-2026","status":"publish","type":"news","link":"https:\/\/www.univ-mosta.dz\/vrpghr\/news\/avis-de-soutenance-de-these-de-doctorat-madame-founas-fatima-zohra-le-08-juillet-2026\/","title":{"rendered":"Avis de soutenance de th\u00e8se de doctorat : Madame FOUNAS Fatima Zohra, Le \u00ab\u00a008 Juillet 2026\u00a0\u00bb"},"content":{"rendered":"\n<p class=\"has-text-align-center has-text-color has-link-color has-georgia-font-family has-custom-font wp-elements-14c1afb0910a7e60c0f4cf4a8af261a0 wp-block-paragraph\" style=\"color:#f20c91a1;font-family:Georgia;font-size:21px\"><strong>Avis de soutenance de th\u00e8se de doctorat : Madame FOUNAS Fatima Zohra<\/strong><\/p>\n\n\n\n<p class=\"has-georgia-font-family has-custom-font wp-block-paragraph\" style=\"font-family:Georgia;font-size:19px\">II est porte a la connaissance de la communaut\u00e9 universitaire que la soutenance de doctorat de Madame <strong><strong><strong>FOUNAS Fatima Zohra<\/strong><\/strong><\/strong>.<\/p>\n\n\n\n<p class=\"has-text-align-center has-georgia-font-family has-custom-font wp-block-paragraph\" style=\"font-family:Georgia;font-size:19px\">Le <strong>08 Juillet 2026<\/strong><\/p>\n\n\n<div class=\"wp-block-pdfemb-pdf-embedder-viewer\"><a href=\"https:\/\/www.univ-mosta.dz\/vrpghr\/wp-content\/uploads\/sites\/14\/2026\/06\/\u0627\u0639\u0644\u0627\u0646-\u0645\u0646\u0627\u0642\u0634\u0629-\u0623\u0637\u0631\u0648\u062d\u0629-\u0627\u0644\u062f\u0643\u062a\u0648\u0631\u0627\u0647-\u0641\u0648\u0646\u0627\u0633-\u0641\u0627\u0637\u0645\u0629-\u0627\u0644\u0632\u0647\u0631\u0629-08-\u062c\u0648\u064a\u0644\u064a\u0629-2026.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"both\" data-toolbar-fixed=\"on\">\u0627\u0639\u0644\u0627\u0646-\u0645\u0646\u0627\u0642\u0634\u0629-\u0623\u0637\u0631\u0648\u062d\u0629-\u0627\u0644\u062f\u0643\u062a\u0648\u0631\u0627\u0647-\u0641\u0648\u0646\u0627\u0633-\u0641\u0627\u0637\u0645\u0629-\u0627\u0644\u0632\u0647\u0631\u0629-08-\u062c\u0648\u064a\u0644\u064a\u0629-2026<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Avis de soutenance de th\u00e8se de doctorat : Madame FOUNAS Fatima Zohra II est porte a la connaissance de la communaut\u00e9 universitaire que la soutenance de doctorat de Madame FOUNAS Fatima Zohra. Le 08 Juillet 2026 \u0627\u0639\u0644\u0627\u0646-\u0645\u0646\u0627\u0642\u0634\u0629-\u0623\u0637\u0631\u0648\u062d\u0629-\u0627\u0644\u062f\u0643\u062a\u0648\u0631\u0627\u0647-\u0641\u0648\u0646\u0627\u0633-\u0641\u0627\u0637\u0645\u0629-\u0627\u0644\u0632\u0647\u0631\u0629-08-\u062c\u0648\u064a\u0644\u064a\u0629-2026<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"news-category":[112],"class_list":["post-6908","news","type-news","status-publish","hentry","news-category-soutenance-de-these-de-doctorat"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avis de soutenance de th\u00e8se de doctorat : Madame FOUNAS Fatima Zohra, Le &quot;08 Juillet 2026&quot; - Vice-rectorat de la Formation Sup\u00e9rieure de Troisi\u00e8me Cycle, l&#039;Habilitation Universitaire et la Recherche Scientifique, et la Formation Sup\u00e9rieure de Post-Graduation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.univ-mosta.dz\/vrpghr\/news\/avis-de-soutenance-de-these-de-doctorat-madame-founas-fatima-zohra-le-08-juillet-2026\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avis de soutenance de th\u00e8se de doctorat : Madame FOUNAS Fatima Zohra, Le &quot;08 Juillet 2026&quot; - Vice-rectorat de la Formation Sup\u00e9rieure de Troisi\u00e8me Cycle, l&#039;Habilitation Universitaire et la Recherche Scientifique, et la Formation Sup\u00e9rieure de Post-Graduation\" \/>\n<meta property=\"og:description\" content=\"Avis de soutenance de th\u00e8se de doctorat : Madame FOUNAS Fatima Zohra II est porte a la connaissance de la communaut\u00e9 universitaire que la soutenance de doctorat de Madame FOUNAS Fatima Zohra. Le 08 Juillet 2026 \u0627\u0639\u0644\u0627\u0646-\u0645\u0646\u0627\u0642\u0634\u0629-\u0623\u0637\u0631\u0648\u062d\u0629-\u0627\u0644\u062f\u0643\u062a\u0648\u0631\u0627\u0647-\u0641\u0648\u0646\u0627\u0633-\u0641\u0627\u0637\u0645\u0629-\u0627\u0644\u0632\u0647\u0631\u0629-08-\u062c\u0648\u064a\u0644\u064a\u0629-2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.univ-mosta.dz\/vrpghr\/news\/avis-de-soutenance-de-these-de-doctorat-madame-founas-fatima-zohra-le-08-juillet-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Vice-rectorat de la Formation Sup\u00e9rieure de Troisi\u00e8me Cycle, l&#039;Habilitation Universitaire et la Recherche Scientifique, et la Formation Sup\u00e9rieure de Post-Graduation\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-01T13:49:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.univ-mosta.dz\\\/vrpghr\\\/news\\\/avis-de-soutenance-de-these-de-doctorat-madame-founas-fatima-zohra-le-08-juillet-2026\\\/\",\"url\":\"https:\\\/\\\/www.univ-mosta.dz\\\/vrpghr\\\/news\\\/avis-de-soutenance-de-these-de-doctorat-madame-founas-fatima-zohra-le-08-juillet-2026\\\/\",\"name\":\"Avis de soutenance de th\u00e8se de doctorat : Madame FOUNAS Fatima Zohra, Le \\\"08 Juillet 2026\\\" - Vice-rectorat de la Formation Sup\u00e9rieure de Troisi\u00e8me Cycle, l&#039;Habilitation Universitaire et la Recherche Scientifique, et la Formation Sup\u00e9rieure de Post-Graduation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.univ-mosta.dz\\\/vrpghr\\\/#website\"},\"datePublished\":\"2026-06-15T07:45:00+00:00\",\"dateModified\":\"2026-07-01T13:49:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.univ-mosta.dz\\\/vrpghr\\\/news\\\/avis-de-soutenance-de-these-de-doctorat-madame-founas-fatima-zohra-le-08-juillet-2026\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.univ-mosta.dz\\\/vrpghr\\\/news\\\/avis-de-soutenance-de-these-de-doctorat-madame-founas-fatima-zohra-le-08-juillet-2026\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.univ-mosta.dz\\\/vrpghr\\\/news\\\/avis-de-soutenance-de-these-de-doctorat-madame-founas-fatima-zohra-le-08-juillet-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.univ-mosta.dz\\\/vrpghr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.univ-mosta.dz\\\/vrpghr\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Avis de soutenance de th\u00e8se de doctorat : Madame FOUNAS Fatima Zohra, Le \u00ab\u00a008 Juillet 2026\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.univ-mosta.dz\\\/vrpghr\\\/#website\",\"url\":\"https:\\\/\\\/www.univ-mosta.dz\\\/vrpghr\\\/\",\"name\":\"Vice-rectorat de la Formation Sup\u00e9rieure de Troisi\u00e8me Cycle, l&#039;Habilitation Universitaire et la Recherche Scientifique, et la Formation Sup\u00e9rieure de Post-Graduation\",\"description\":\"Universit\u00e9 Abdelhamid Ibn Badis - Mostaganem\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.univ-mosta.dz\\\/vrpghr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avis de soutenance de th\u00e8se de doctorat : Madame FOUNAS Fatima Zohra, Le \"08 Juillet 2026\" - Vice-rectorat de la Formation Sup\u00e9rieure de Troisi\u00e8me Cycle, l&#039;Habilitation Universitaire et la Recherche Scientifique, et la Formation Sup\u00e9rieure de Post-Graduation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.univ-mosta.dz\/vrpghr\/news\/avis-de-soutenance-de-these-de-doctorat-madame-founas-fatima-zohra-le-08-juillet-2026\/","og_locale":"fr_FR","og_type":"article","og_title":"Avis de soutenance de th\u00e8se de doctorat : Madame FOUNAS Fatima Zohra, Le \"08 Juillet 2026\" - Vice-rectorat de la Formation Sup\u00e9rieure de Troisi\u00e8me Cycle, l&#039;Habilitation Universitaire et la Recherche Scientifique, et la Formation Sup\u00e9rieure de Post-Graduation","og_description":"Avis de soutenance de th\u00e8se de doctorat : Madame FOUNAS Fatima Zohra II est porte a la connaissance de la communaut\u00e9 universitaire que la soutenance de doctorat de Madame FOUNAS Fatima Zohra. Le 08 Juillet 2026 \u0627\u0639\u0644\u0627\u0646-\u0645\u0646\u0627\u0642\u0634\u0629-\u0623\u0637\u0631\u0648\u062d\u0629-\u0627\u0644\u062f\u0643\u062a\u0648\u0631\u0627\u0647-\u0641\u0648\u0646\u0627\u0633-\u0641\u0627\u0637\u0645\u0629-\u0627\u0644\u0632\u0647\u0631\u0629-08-\u062c\u0648\u064a\u0644\u064a\u0629-2026","og_url":"https:\/\/www.univ-mosta.dz\/vrpghr\/news\/avis-de-soutenance-de-these-de-doctorat-madame-founas-fatima-zohra-le-08-juillet-2026\/","og_site_name":"Vice-rectorat de la Formation Sup\u00e9rieure de Troisi\u00e8me Cycle, l&#039;Habilitation Universitaire et la Recherche Scientifique, et la Formation Sup\u00e9rieure de Post-Graduation","article_modified_time":"2026-07-01T13:49:19+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.univ-mosta.dz\/vrpghr\/news\/avis-de-soutenance-de-these-de-doctorat-madame-founas-fatima-zohra-le-08-juillet-2026\/","url":"https:\/\/www.univ-mosta.dz\/vrpghr\/news\/avis-de-soutenance-de-these-de-doctorat-madame-founas-fatima-zohra-le-08-juillet-2026\/","name":"Avis de soutenance de th\u00e8se de doctorat : Madame FOUNAS Fatima Zohra, Le \"08 Juillet 2026\" - Vice-rectorat de la Formation Sup\u00e9rieure de Troisi\u00e8me Cycle, l&#039;Habilitation Universitaire et la Recherche Scientifique, et la Formation Sup\u00e9rieure de Post-Graduation","isPartOf":{"@id":"https:\/\/www.univ-mosta.dz\/vrpghr\/#website"},"datePublished":"2026-06-15T07:45:00+00:00","dateModified":"2026-07-01T13:49:19+00:00","breadcrumb":{"@id":"https:\/\/www.univ-mosta.dz\/vrpghr\/news\/avis-de-soutenance-de-these-de-doctorat-madame-founas-fatima-zohra-le-08-juillet-2026\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.univ-mosta.dz\/vrpghr\/news\/avis-de-soutenance-de-these-de-doctorat-madame-founas-fatima-zohra-le-08-juillet-2026\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.univ-mosta.dz\/vrpghr\/news\/avis-de-soutenance-de-these-de-doctorat-madame-founas-fatima-zohra-le-08-juillet-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.univ-mosta.dz\/vrpghr\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.univ-mosta.dz\/vrpghr\/news\/"},{"@type":"ListItem","position":3,"name":"Avis de soutenance de th\u00e8se de doctorat : Madame FOUNAS Fatima Zohra, Le \u00ab\u00a008 Juillet 2026\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.univ-mosta.dz\/vrpghr\/#website","url":"https:\/\/www.univ-mosta.dz\/vrpghr\/","name":"Vice-rectorat de la Formation Sup\u00e9rieure de Troisi\u00e8me Cycle, l&#039;Habilitation Universitaire et la Recherche Scientifique, et la Formation Sup\u00e9rieure de Post-Graduation","description":"Universit\u00e9 Abdelhamid Ibn Badis - Mostaganem","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.univ-mosta.dz\/vrpghr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.univ-mosta.dz\/vrpghr\/wp-json\/wp\/v2\/news\/6908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.univ-mosta.dz\/vrpghr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.univ-mosta.dz\/vrpghr\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/www.univ-mosta.dz\/vrpghr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.univ-mosta.dz\/vrpghr\/wp-json\/wp\/v2\/comments?post=6908"}],"version-history":[{"count":1,"href":"https:\/\/www.univ-mosta.dz\/vrpghr\/wp-json\/wp\/v2\/news\/6908\/revisions"}],"predecessor-version":[{"id":6909,"href":"https:\/\/www.univ-mosta.dz\/vrpghr\/wp-json\/wp\/v2\/news\/6908\/revisions\/6909"}],"wp:attachment":[{"href":"https:\/\/www.univ-mosta.dz\/vrpghr\/wp-json\/wp\/v2\/media?parent=6908"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.univ-mosta.dz\/vrpghr\/wp-json\/wp\/v2\/tags?post=6908"},{"taxonomy":"news-category","embeddable":true,"href":"https:\/\/www.univ-mosta.dz\/vrpghr\/wp-json\/wp\/v2\/news-category?post=6908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}