{"id":929,"date":"2021-12-01T09:18:54","date_gmt":"2021-12-01T08:18:54","guid":{"rendered":"https:\/\/www.univ-mosta.dz\/medecine\/?p=929"},"modified":"2026-04-30T15:48:22","modified_gmt":"2026-04-30T13:48:22","slug":"module-cytologie","status":"publish","type":"post","link":"https:\/\/www.univ-mosta.dz\/medecine\/module-cytologie\/","title":{"rendered":"Module : Anatomie"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" width=\"275\" height=\"183\" class=\"wp-image-936\" style=\"width: 300px\" src=\"http:\/\/www.univ-mosta.dz\/medecine\/wp-content\/uploads\/sites\/4\/2021\/12\/telechargement-1-1.jpg\" alt=\"\"><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Chapitre<\/strong><\/td><td><strong>Objectifs<\/strong><\/td><td><strong>Volume horaire<\/strong><\/td><\/tr><tr><td>&#8211;&nbsp;&nbsp; G\u00e9n\u00e9ralit\u00e9s sur l&rsquo;anatomie : &#8211; G\u00e9n\u00e9ralit\u00e9s&nbsp;&nbsp;&nbsp; sur&nbsp;&nbsp;&nbsp; le&nbsp;&nbsp;&nbsp; corps<br>humain&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (langage<br>anatomique) &#8211;&nbsp;&nbsp; G\u00e9n\u00e9ralit\u00e9s sur les os. &#8211; G\u00e9n\u00e9ralit\u00e9s&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; sur&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; les<br>articulations. &#8211;&nbsp;&nbsp; G\u00e9n\u00e9ralit\u00e9s sur les muscles. &#8211;&nbsp;&nbsp; G\u00e9n\u00e9ralit\u00e9s sur les vaisseaux &#8211; G\u00e9n\u00e9ralit\u00e9s&nbsp;&nbsp; sur&nbsp; le&nbsp;&nbsp; syst\u00e8me<br>nerveux.<\/td><td>&#8211;&nbsp;&nbsp;&nbsp; Histoire de l&rsquo;anatomie. &#8211;&nbsp; Place de l&rsquo;\u00eatre humain dans le r\u00e8gne<br>animal (mammif\u00e8res). &#8211;&nbsp; Conna\u00eetre&nbsp; la&nbsp; position&nbsp; anatomique&nbsp; de<br>r\u00e9f\u00e9rence du corps humain. &#8211;&nbsp; Conna\u00eetre&nbsp;&nbsp; les&nbsp;&nbsp; axes&nbsp;&nbsp; anatomiques&nbsp;&nbsp; de<br>r\u00e9f\u00e9rence. &#8211;&nbsp;&nbsp;&nbsp; Conna\u00eetre les plans de r\u00e9f\u00e9rence. &#8211;&nbsp;&nbsp;&nbsp; Conna\u00eetre la nomenclature anatomique. &#8211;&nbsp; Conna\u00eetre&nbsp;&nbsp; l&rsquo;organisation&nbsp;&nbsp; g\u00e9n\u00e9rale&nbsp;&nbsp; du<br>corps humain. &#8211;&nbsp;&nbsp;&nbsp; Conna\u00eetre la partie osseuse du squelette. &#8211;&nbsp;&nbsp;&nbsp; Conna\u00eetre la partie axiale du squelette. &#8211;&nbsp; Conna\u00eetre la partie appendiculaire du<br>squelette. &#8211;&nbsp; Conna\u00eetre&nbsp; la&nbsp; partie&nbsp; cartilagineuse&nbsp; du<br>squelette. &#8211;&nbsp; Conna\u00eetre&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; la&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; classification&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; des<br>articulations. &#8211;&nbsp; Conna\u00eetre&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; les&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; structures<br>d&rsquo;amortissement des pressions. &#8211;&nbsp; Conna\u00eetre&nbsp; les&nbsp;&nbsp; structures&nbsp; d&rsquo;adaptation<br>des surfaces articulaires. &#8211;&nbsp;&nbsp;&nbsp; Conna\u00eetre les structures de glissement &#8211;&nbsp;&nbsp;&nbsp; Conna\u00eetre la statique articulaire. &#8211;&nbsp; Conna\u00eetre&nbsp;&nbsp;&nbsp; les&nbsp;&nbsp;&nbsp; diff\u00e9rents&nbsp;&nbsp;&nbsp; types&nbsp;&nbsp;&nbsp; de<br>muscles existant dans le corps humain. &#8211;&nbsp; Conna\u00eetre&nbsp;&nbsp;&nbsp;&nbsp; la&nbsp;&nbsp;&nbsp; forme&nbsp;&nbsp;&nbsp;&nbsp; d&rsquo;un&nbsp;&nbsp;&nbsp;&nbsp; muscle<br>squelettique. &#8211;&nbsp;&nbsp;&nbsp; Conna\u00eetre les annexes du muscle. &#8211;&nbsp; Conna\u00eetre&nbsp; la structure&nbsp; macroscopique<br>du muscle. &#8211;&nbsp; Conna\u00eetre&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; l&rsquo;organisation&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; et&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; la<br>distribution&nbsp;&nbsp;&nbsp;&nbsp; g\u00e9n\u00e9rale&nbsp;&nbsp;&nbsp;&nbsp; du&nbsp;&nbsp;&nbsp;&nbsp; syst\u00e8me<br>circulatoire.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &#8211;&nbsp; Conna\u00eetre&nbsp;&nbsp; l&rsquo;organisation g\u00e9n\u00e9rale du syst\u00e8me nerveux.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &#8211;&nbsp; Conna\u00eetre le&nbsp; syst\u00e8me nerveux central et p\u00e9riph\u00e9rique&nbsp;; la nature du nerf<br>mixte sensitif (cutan\u00e9e),<\/td><td><strong>8h<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Chapitre<\/strong><\/td><td><strong>Objectifs<\/strong><\/td><td><strong>Volume horaire<\/strong><\/td><\/tr><tr><td><strong>Cours <\/strong>: Ost\u00e9ologie du membre thoracique (sup\u00e9rieur)<\/td><td>&#8211;&nbsp;&nbsp; Reconna\u00eetre les diff\u00e9rents os du membre. &#8211;&nbsp;&nbsp; Classer l&rsquo;os selon sa morphologie. &#8211;&nbsp;&nbsp; D\u00e9crire la morphologie d&rsquo;un os. &#8211;&nbsp;&nbsp; Placer&nbsp;&nbsp;&nbsp; correctement&nbsp;&nbsp; un&nbsp;&nbsp;&nbsp; os&nbsp;&nbsp;&nbsp; sur&nbsp;&nbsp; le<br>membre. &#8211;&nbsp;&nbsp; Conna\u00eetre&nbsp;&nbsp; les&nbsp;&nbsp; diff\u00e9rents&nbsp;&nbsp; os&nbsp;&nbsp; et&nbsp;&nbsp; leurs<br>\u00e9l\u00e9ments sur un clich\u00e9 radiologique.<\/td><td><strong>4 h 30mn<\/strong><\/td><\/tr><tr><td><strong>Cours <\/strong>: Arthrologie du membre thoracique&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (sup\u00e9rieur) Articulations : de l&rsquo;\u00e9paule, du coude, du poignet.<\/td><td>&#8211;&nbsp;&nbsp; Savoir classer une articulation (type). &#8211;&nbsp;&nbsp; Conna\u00eetre&nbsp;&nbsp;&nbsp; les&nbsp;&nbsp;&nbsp; surfaces&nbsp;&nbsp;&nbsp; articulaires<br>formant une articulation. &#8211;&nbsp;&nbsp; Conna\u00eetre les moyens d&rsquo;union passifs. &#8211;&nbsp;&nbsp; Conna\u00eetre les moyens d&rsquo;union actifs. &#8211;&nbsp;&nbsp; Conna\u00eetre&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; les&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; diff\u00e9rents&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; axes<br>et mouvements de l&rsquo;articulation.<\/td><td><strong>4 hSOmin<\/strong><\/td><\/tr><tr><td><strong>Cours <\/strong>: Myologie du membre thoracique&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (sup\u00e9rieur)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; : Muscles de l&rsquo;\u00e9paule, du bras, de l&rsquo;avant-bras, de la main.<\/td><td>&#8211;&nbsp;&nbsp; Conna\u00eetre&nbsp; les&nbsp; muscles&nbsp; des&nbsp; diff\u00e9rentes<br>r\u00e9gions du membre. &#8211;&nbsp;&nbsp; Etre capable de classer les muscles selon<br>leurs actions. &#8211;&nbsp;&nbsp; Conna\u00eetre leur innervation.<\/td><td><strong>4h30min<\/strong><\/td><\/tr><tr><td><strong>Cours&nbsp;&nbsp;&nbsp; <\/strong>:&nbsp;&nbsp;&nbsp; Vascularisation&nbsp;&nbsp; du membre&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;thoracique (sup\u00e9rieur)&nbsp;&nbsp;&nbsp;&nbsp; <strong><em>Les&nbsp;&nbsp;&nbsp; art\u00e8res&nbsp;&nbsp;&nbsp; <\/em><\/strong>; axillaire,&nbsp;&nbsp;&nbsp; brachiale,&nbsp;&nbsp;&nbsp; radiale et ulnaire. Les art\u00e8res de la main. <strong><em>Drainage&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; veineux&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; et lymphatique.<\/em><\/strong><\/td><td>&#8211;&nbsp;&nbsp; Conna\u00eetre&nbsp;&nbsp;&nbsp; l&rsquo;origine,&nbsp;&nbsp;&nbsp; le&nbsp;&nbsp;&nbsp; trajet&nbsp;&nbsp;&nbsp; et&nbsp;&nbsp; la<br>terminaison de chaque art\u00e8re. &#8211;&nbsp;&nbsp; Conna\u00eetre leurs rapports intimes avec<br>les&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u00e9l\u00e9ments&nbsp;&nbsp;&nbsp;&nbsp; vasculo-nerveux&nbsp;&nbsp;&nbsp;&nbsp; de<br>voisinage &#8211;&nbsp;&nbsp; Conna\u00eetre&nbsp;&nbsp;&nbsp; leurs&nbsp;&nbsp;&nbsp; rapports&nbsp;&nbsp;&nbsp; avec&nbsp;&nbsp;&nbsp; les<br>\u00e9l\u00e9ments&nbsp;&nbsp; musculaires&nbsp;&nbsp; ou&nbsp;&nbsp; tendineux<br>pouvant&nbsp;&nbsp;&nbsp; \u00eatre&nbsp;&nbsp;&nbsp;&nbsp; \u00e0&nbsp;&nbsp;&nbsp; l&rsquo;origine&nbsp;&nbsp;&nbsp; de&nbsp;&nbsp;&nbsp; leur<br>compression. &#8211;&nbsp;&nbsp; Diff\u00e9rencier entre veines superficielle et<br>profonde.<\/td><td><strong>6h<\/strong><\/td><\/tr><tr><td><strong>Cours&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/strong>Innervation&nbsp;&nbsp;&nbsp;&nbsp; du membre&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; thoracique (sup\u00e9rieur). Plexus brachial, et branches terminales : Nerf m\u00e9dian, Nerf ulnaire, Nerf musculo-cutan\u00e9, Nerf radial, nerf axillaire, Nerf cutan\u00e9 m\u00e9dial de l&rsquo;avant-bras, Nerf cutan\u00e9 m\u00e9dial du bras.<\/td><td>&#8211;\u00a0\u00a0\u00a0 Conna\u00eetre la situation et la constitution<br>du plexus brachial. &#8211;\u00a0\u00a0\u00a0 Conna\u00eetre\u00a0\u00a0\u00a0 l&rsquo;origine,\u00a0\u00a0\u00a0 le\u00a0\u00a0\u00a0 trajet\u00a0\u00a0\u00a0 et\u00a0\u00a0\u00a0 la<br>terminaison de chaque nerf &#8211;\u00a0\u00a0\u00a0 Conna\u00eetre leurs rapports intimes avec<br>les\u00a0\u00a0\u00a0\u00a0 \u00e9l\u00e9ments\u00a0\u00a0\u00a0\u00a0 vasculo-nerveux\u00a0\u00a0\u00a0\u00a0 de<br>voisinage &#8211;\u00a0\u00a0\u00a0 Conna\u00eetre le territoire d&rsquo;innervalien-des.<br>diff\u00e9rents nerfs\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 &#8211;\u00a0\u00a0\u00a0 Conna\u00eetre\u00a0\u00a0\u00a0 leurs\u00a0\u00a0\u00a0<br>\u00e9l\u00e9ments osseux pouvanvotna<br>de leur compression ou  Comment explorer un nerf<\/td><td><strong>6 h<\/strong> &nbsp; &nbsp;<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ChapitreObjectifsVolume horaire&#8211;&nbsp;&nbsp; G\u00e9n\u00e9ralit\u00e9s sur l&rsquo;anatomie : &#8211; G\u00e9n\u00e9ralit\u00e9s&nbsp;&nbsp;&nbsp; sur&nbsp;&nbsp;&nbsp; le&nbsp;&nbsp;&nbsp; corpshumain&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (langageanatomique) &#8211;&nbsp;&nbsp; G\u00e9n\u00e9ralit\u00e9s sur les os. &#8211; G\u00e9n\u00e9ralit\u00e9s&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; sur&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; lesarticulations. &#8211;&nbsp;&nbsp; G\u00e9n\u00e9ralit\u00e9s sur les muscles. &#8211;&nbsp;&nbsp; G\u00e9n\u00e9ralit\u00e9s sur les vaisseaux &#8211; G\u00e9n\u00e9ralit\u00e9s&nbsp;&nbsp; sur&nbsp; le&nbsp;&nbsp; syst\u00e8menerveux.&#8211;&nbsp;&nbsp;&nbsp; Histoire de l&rsquo;anatomie. &#8211;&nbsp; Place de l&rsquo;\u00eatre humain dans le r\u00e8gneanimal (mammif\u00e8res). &#8211;&nbsp; Conna\u00eetre&nbsp; la&nbsp; position&nbsp; anatomique&nbsp; der\u00e9f\u00e9rence du &hellip;<\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[34],"tags":[],"class_list":["post-929","post","type-post","status-publish","format-standard","hentry","category-programmes-1ere-annnee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Module : Anatomie - Facult\u00e9 de M\u00e9decine Mostaganem | Universit\u00e9 Abdelhamid Ibn Badis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.univ-mosta.dz\/medecine\/module-cytologie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Module : Anatomie - Facult\u00e9 de M\u00e9decine Mostaganem | Universit\u00e9 Abdelhamid Ibn Badis\" \/>\n<meta property=\"og:description\" content=\"ChapitreObjectifsVolume horaire&#8211;&nbsp;&nbsp; G\u00e9n\u00e9ralit\u00e9s sur l&rsquo;anatomie : &#8211; G\u00e9n\u00e9ralit\u00e9s&nbsp;&nbsp;&nbsp; sur&nbsp;&nbsp;&nbsp; le&nbsp;&nbsp;&nbsp; corpshumain&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (langageanatomique) &#8211;&nbsp;&nbsp; G\u00e9n\u00e9ralit\u00e9s sur les os. &#8211; G\u00e9n\u00e9ralit\u00e9s&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; sur&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; lesarticulations. &#8211;&nbsp;&nbsp; G\u00e9n\u00e9ralit\u00e9s sur les muscles. &#8211;&nbsp;&nbsp; G\u00e9n\u00e9ralit\u00e9s sur les vaisseaux &#8211; G\u00e9n\u00e9ralit\u00e9s&nbsp;&nbsp; sur&nbsp; le&nbsp;&nbsp; syst\u00e8menerveux.&#8211;&nbsp;&nbsp;&nbsp; Histoire de l&rsquo;anatomie. &#8211;&nbsp; Place de l&rsquo;\u00eatre humain dans le r\u00e8gneanimal (mammif\u00e8res). &#8211;&nbsp; Conna\u00eetre&nbsp; la&nbsp; position&nbsp; anatomique&nbsp; der\u00e9f\u00e9rence du &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.univ-mosta.dz\/medecine\/module-cytologie\/\" \/>\n<meta property=\"og:site_name\" content=\"Facult\u00e9 de M\u00e9decine Mostaganem | Universit\u00e9 Abdelhamid Ibn Badis\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-01T08:18:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-30T13:48:22+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.univ-mosta.dz\/medecine\/wp-content\/uploads\/sites\/4\/2021\/12\/telechargement-1-1.jpg\" \/>\n<meta name=\"author\" content=\"Facult\u00e9 de m\u00e9d\u00e9cine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Facult\u00e9 de m\u00e9d\u00e9cine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/module-cytologie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/module-cytologie\\\/\"},\"author\":{\"name\":\"Facult\u00e9 de m\u00e9d\u00e9cine\",\"@id\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/#\\\/schema\\\/person\\\/f4f9ce25c8c7afaf166989176652681b\"},\"headline\":\"Module : Anatomie\",\"datePublished\":\"2021-12-01T08:18:54+00:00\",\"dateModified\":\"2026-04-30T13:48:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/module-cytologie\\\/\"},\"wordCount\":1143,\"image\":{\"@id\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/module-cytologie\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/12\\\/telechargement-1-1.jpg\",\"articleSection\":[\"Programmes 1\u00e8re Annn\u00e9e\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/module-cytologie\\\/\",\"url\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/module-cytologie\\\/\",\"name\":\"Module : Anatomie - Facult\u00e9 de M\u00e9decine Mostaganem | Universit\u00e9 Abdelhamid Ibn Badis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/module-cytologie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/module-cytologie\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/12\\\/telechargement-1-1.jpg\",\"datePublished\":\"2021-12-01T08:18:54+00:00\",\"dateModified\":\"2026-04-30T13:48:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/#\\\/schema\\\/person\\\/f4f9ce25c8c7afaf166989176652681b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/module-cytologie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/module-cytologie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/module-cytologie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/12\\\/telechargement-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/12\\\/telechargement-1-1.jpg\",\"width\":275,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/module-cytologie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Module : Anatomie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/#website\",\"url\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/\",\"name\":\"Facult\u00e9 de M\u00e9decine Mostaganem | Universit\u00e9 Abdelhamid Ibn Badis\",\"description\":\"Site officiel de la Facult\u00e9 de M\u00e9decine de Mostaganem \u2013 Universit\u00e9 Abdelhamid Ibn Badis. Actualit\u00e9s, programmes, concours, r\u00e9sidanat et informations pour les \u00e9tudiants.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/#\\\/schema\\\/person\\\/f4f9ce25c8c7afaf166989176652681b\",\"name\":\"Facult\u00e9 de m\u00e9d\u00e9cine\",\"url\":\"https:\\\/\\\/www.univ-mosta.dz\\\/medecine\\\/author\\\/fmedumab\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Module : Anatomie - Facult\u00e9 de M\u00e9decine Mostaganem | Universit\u00e9 Abdelhamid Ibn Badis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.univ-mosta.dz\/medecine\/module-cytologie\/","og_locale":"fr_FR","og_type":"article","og_title":"Module : Anatomie - Facult\u00e9 de M\u00e9decine Mostaganem | Universit\u00e9 Abdelhamid Ibn Badis","og_description":"ChapitreObjectifsVolume horaire&#8211;&nbsp;&nbsp; G\u00e9n\u00e9ralit\u00e9s sur l&rsquo;anatomie : &#8211; G\u00e9n\u00e9ralit\u00e9s&nbsp;&nbsp;&nbsp; sur&nbsp;&nbsp;&nbsp; le&nbsp;&nbsp;&nbsp; corpshumain&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; (langageanatomique) &#8211;&nbsp;&nbsp; G\u00e9n\u00e9ralit\u00e9s sur les os. &#8211; G\u00e9n\u00e9ralit\u00e9s&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; sur&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; lesarticulations. &#8211;&nbsp;&nbsp; G\u00e9n\u00e9ralit\u00e9s sur les muscles. &#8211;&nbsp;&nbsp; G\u00e9n\u00e9ralit\u00e9s sur les vaisseaux &#8211; G\u00e9n\u00e9ralit\u00e9s&nbsp;&nbsp; sur&nbsp; le&nbsp;&nbsp; syst\u00e8menerveux.&#8211;&nbsp;&nbsp;&nbsp; Histoire de l&rsquo;anatomie. &#8211;&nbsp; Place de l&rsquo;\u00eatre humain dans le r\u00e8gneanimal (mammif\u00e8res). &#8211;&nbsp; Conna\u00eetre&nbsp; la&nbsp; position&nbsp; anatomique&nbsp; der\u00e9f\u00e9rence du &hellip;","og_url":"https:\/\/www.univ-mosta.dz\/medecine\/module-cytologie\/","og_site_name":"Facult\u00e9 de M\u00e9decine Mostaganem | Universit\u00e9 Abdelhamid Ibn Badis","article_published_time":"2021-12-01T08:18:54+00:00","article_modified_time":"2026-04-30T13:48:22+00:00","og_image":[{"url":"http:\/\/www.univ-mosta.dz\/medecine\/wp-content\/uploads\/sites\/4\/2021\/12\/telechargement-1-1.jpg","type":"","width":"","height":""}],"author":"Facult\u00e9 de m\u00e9d\u00e9cine","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Facult\u00e9 de m\u00e9d\u00e9cine","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.univ-mosta.dz\/medecine\/module-cytologie\/#article","isPartOf":{"@id":"https:\/\/www.univ-mosta.dz\/medecine\/module-cytologie\/"},"author":{"name":"Facult\u00e9 de m\u00e9d\u00e9cine","@id":"https:\/\/www.univ-mosta.dz\/medecine\/#\/schema\/person\/f4f9ce25c8c7afaf166989176652681b"},"headline":"Module : Anatomie","datePublished":"2021-12-01T08:18:54+00:00","dateModified":"2026-04-30T13:48:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.univ-mosta.dz\/medecine\/module-cytologie\/"},"wordCount":1143,"image":{"@id":"https:\/\/www.univ-mosta.dz\/medecine\/module-cytologie\/#primaryimage"},"thumbnailUrl":"http:\/\/www.univ-mosta.dz\/medecine\/wp-content\/uploads\/sites\/4\/2021\/12\/telechargement-1-1.jpg","articleSection":["Programmes 1\u00e8re Annn\u00e9e"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.univ-mosta.dz\/medecine\/module-cytologie\/","url":"https:\/\/www.univ-mosta.dz\/medecine\/module-cytologie\/","name":"Module : Anatomie - Facult\u00e9 de M\u00e9decine Mostaganem | Universit\u00e9 Abdelhamid Ibn Badis","isPartOf":{"@id":"https:\/\/www.univ-mosta.dz\/medecine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.univ-mosta.dz\/medecine\/module-cytologie\/#primaryimage"},"image":{"@id":"https:\/\/www.univ-mosta.dz\/medecine\/module-cytologie\/#primaryimage"},"thumbnailUrl":"http:\/\/www.univ-mosta.dz\/medecine\/wp-content\/uploads\/sites\/4\/2021\/12\/telechargement-1-1.jpg","datePublished":"2021-12-01T08:18:54+00:00","dateModified":"2026-04-30T13:48:22+00:00","author":{"@id":"https:\/\/www.univ-mosta.dz\/medecine\/#\/schema\/person\/f4f9ce25c8c7afaf166989176652681b"},"breadcrumb":{"@id":"https:\/\/www.univ-mosta.dz\/medecine\/module-cytologie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.univ-mosta.dz\/medecine\/module-cytologie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.univ-mosta.dz\/medecine\/module-cytologie\/#primaryimage","url":"https:\/\/www.univ-mosta.dz\/medecine\/wp-content\/uploads\/sites\/4\/2021\/12\/telechargement-1-1.jpg","contentUrl":"https:\/\/www.univ-mosta.dz\/medecine\/wp-content\/uploads\/sites\/4\/2021\/12\/telechargement-1-1.jpg","width":275,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/www.univ-mosta.dz\/medecine\/module-cytologie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.univ-mosta.dz\/medecine\/"},{"@type":"ListItem","position":2,"name":"Module : Anatomie"}]},{"@type":"WebSite","@id":"https:\/\/www.univ-mosta.dz\/medecine\/#website","url":"https:\/\/www.univ-mosta.dz\/medecine\/","name":"Facult\u00e9 de M\u00e9decine Mostaganem | Universit\u00e9 Abdelhamid Ibn Badis","description":"Site officiel de la Facult\u00e9 de M\u00e9decine de Mostaganem \u2013 Universit\u00e9 Abdelhamid Ibn Badis. Actualit\u00e9s, programmes, concours, r\u00e9sidanat et informations pour les \u00e9tudiants.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.univ-mosta.dz\/medecine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.univ-mosta.dz\/medecine\/#\/schema\/person\/f4f9ce25c8c7afaf166989176652681b","name":"Facult\u00e9 de m\u00e9d\u00e9cine","url":"https:\/\/www.univ-mosta.dz\/medecine\/author\/fmedumab\/"}]}},"_links":{"self":[{"href":"https:\/\/www.univ-mosta.dz\/medecine\/wp-json\/wp\/v2\/posts\/929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.univ-mosta.dz\/medecine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.univ-mosta.dz\/medecine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.univ-mosta.dz\/medecine\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.univ-mosta.dz\/medecine\/wp-json\/wp\/v2\/comments?post=929"}],"version-history":[{"count":5,"href":"https:\/\/www.univ-mosta.dz\/medecine\/wp-json\/wp\/v2\/posts\/929\/revisions"}],"predecessor-version":[{"id":940,"href":"https:\/\/www.univ-mosta.dz\/medecine\/wp-json\/wp\/v2\/posts\/929\/revisions\/940"}],"wp:attachment":[{"href":"https:\/\/www.univ-mosta.dz\/medecine\/wp-json\/wp\/v2\/media?parent=929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.univ-mosta.dz\/medecine\/wp-json\/wp\/v2\/categories?post=929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.univ-mosta.dz\/medecine\/wp-json\/wp\/v2\/tags?post=929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}